{"id":878,"date":"2023-03-28T10:22:09","date_gmt":"2023-03-28T08:22:09","guid":{"rendered":"https:\/\/bitcamp.it\/blog\/?p=878"},"modified":"2023-11-30T15:13:02","modified_gmt":"2023-11-30T14:13:02","slug":"struttura-di-un-programma-java-guida-completa","status":"publish","type":"post","link":"https:\/\/bitcamp.it\/blog\/blog-corso-java-fondamenti-e-approfondimenti\/struttura-di-un-programma-java-guida-completa\/","title":{"rendered":"Struttura di un programma Java: Guida completa"},"content":{"rendered":"\n<p>Un programma scritto con il linguaggio Java si presenta come un insieme di definizioni di classi. Ogni classe pu\u00f2 essere definita in un file separato dagli altri, ma ci sono anche programmi che risiedono in un unico file. Il file che contiene la classe o l\u2019elenco di classi \u00e8 chiamato unit\u00e0 di compilazione.<\/p>\n\n\n\n<p>Ogni <strong>compilation unit<\/strong> \u00e8 strutturata in pi\u00f9 parti semantiche che vengono combinate insieme:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>una dichiarazione di package (package declaration);<\/li>\n\n\n\n<li>delle dichiarazioni di importazione (import declaration);<\/li>\n\n\n\n<li>delle dichiarazioni dei tipi (type declaration);<\/li>\n<\/ul>\n\n\n\n<p>Secondo un preciso sistema ramificato, ognuna di queste dichiarazioni \u00e8 a sua volta suddivisa in elementi lessicali, quali terminatori di riga, spazi, commenti e token.<\/p>\n\n\n\n<p><strong>Spazi, commenti e token<\/strong> sono definiti come elementi di imput dell\u2019unit\u00e0 di compilazione, ma solo i token sono significativi, mentre spazi e commenti vengono utilizzati solo per separare i token.<\/p>\n\n\n\n<p>Quali sono i token? Rientrano in questa categoria <strong>gli identificatori, le keyword, i letterali (integer, floating-point, boolean, character, string e null), gli operatori e i segni di punteggiatura<\/strong>.<\/p>\n\n\n\n<p>A partire dagli elementi lessicali significativi (token) si costruiscono le statement che sono le istruzioni del programma Java, nello specifico azioni o comandi che devono essere eseguiti durante l\u2019esecuzione di un programma.<\/p>\n\n\n\n<p>Ogni istruzione singola (<strong>single-line statement<\/strong>) deve terminare con il carattere punto e virgola (;) mentre due o pi\u00f9 istruzioni (<strong>multi-line statement<\/strong>) possono essere raggruppate insieme, tra parentesi graffe, a formare un blocco (<strong>block statement<\/strong>).<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/bitcamp.it\/blog\/wp-content\/uploads\/2023\/03\/struttura-java.jpg\" alt=\"Struttura Programma Java\" class=\"wp-image-880\" srcset=\"https:\/\/bitcamp.it\/blog\/wp-content\/uploads\/2023\/03\/struttura-java.jpg 1200w, https:\/\/bitcamp.it\/blog\/wp-content\/uploads\/2023\/03\/struttura-java-300x200.jpg 300w, https:\/\/bitcamp.it\/blog\/wp-content\/uploads\/2023\/03\/struttura-java-1024x683.jpg 1024w, https:\/\/bitcamp.it\/blog\/wp-content\/uploads\/2023\/03\/struttura-java-768x512.jpg 768w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Cosa sono gli identificatori Java<\/h2>\n\n\n\n<p>Gli identificatori Java vengono utilizzati appunto per identificare il codice e scomporlo in pi\u00f9 parti. Si tratta di nomi che possono essere dati alle classi, ai nomi delle variabili o qualsiasi segmento di codice. Ci sono alcune <strong>regole stabilite da Java per la definizione degli identificatori<\/strong>:<\/p>\n\n\n\n<p>-Sono consentiti solo caratteri alfanumerici;<\/p>\n\n\n\n<p>-La sequenza di identificatori dovrebbe sempre iniziare con un carattere;<\/p>\n\n\n\n<p>-Si fa distinzione tra maiuscole e minuscole;<\/p>\n\n\n\n<p>-La lunghezza ottimale di un identificatore \u00e8 compresa tra 4 e 15 lettere.<\/p>\n\n\n\n<p>-Le keyword non possono essere utilizzate come identificatori.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Cosa sono le keyword Java<\/h2>\n\n\n\n<p>Le keyword o parole chiave si presentano come una sequenza di caratteri riservata prefissata dalla sintassi Java che fanno riferimento ad un oggetto o ad un\u2019azione precisa. Ecco le principali <strong>keyword presenti un programma Java<\/strong>:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>ABSTRACT&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;<\/li>\n\n\n\n<li>ASSERT BOOLEAN&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;<\/li>\n\n\n\n<li>BREAK&nbsp;&nbsp;<\/li>\n\n\n\n<li>BYTE&nbsp;&nbsp;&nbsp;&nbsp;<\/li>\n\n\n\n<li>CASE<\/li>\n\n\n\n<li>CATCH&nbsp;<\/li>\n\n\n\n<li>CHAR&nbsp;&nbsp;&nbsp;<\/li>\n\n\n\n<li>CLASS&nbsp;&nbsp;&nbsp;<\/li>\n\n\n\n<li>CONST&nbsp;<\/li>\n\n\n\n<li>CONTINUE&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;<\/li>\n\n\n\n<li>DEFAULT<\/li>\n\n\n\n<li>DO&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;<\/li>\n\n\n\n<li>DOUBLE<\/li>\n\n\n\n<li>ELSE&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;<\/li>\n\n\n\n<li>ENUM&nbsp;&nbsp;<\/li>\n\n\n\n<li>EXPORTS2&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;<\/li>\n\n\n\n<li>EXTENDS<\/li>\n\n\n\n<li>FINAL&nbsp;&nbsp;&nbsp;<\/li>\n\n\n\n<li>FINALLY&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;<\/li>\n\n\n\n<li>FLOAT&nbsp;&nbsp;<\/li>\n\n\n\n<li>FOR&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;<\/li>\n\n\n\n<li>IF&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;<\/li>\n\n\n\n<li>GOTO<\/li>\n\n\n\n<li>IMPLEMENTS&nbsp;&nbsp;&nbsp;&nbsp;<\/li>\n\n\n\n<li>IMPORT&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;<\/li>\n\n\n\n<li>INSTANCEOF&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;<\/li>\n\n\n\n<li>INT&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;<\/li>\n\n\n\n<li>INTERFACE&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;<\/li>\n\n\n\n<li>LONG<\/li>\n\n\n\n<li>MODULE&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;<\/li>\n\n\n\n<li>NATIVE NEW&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;<\/li>\n\n\n\n<li>OPEN, OPENS&nbsp;&nbsp;&nbsp;<\/li>\n\n\n\n<li>PACKAGE&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;<\/li>\n\n\n\n<li>PRIVATE<\/li>\n\n\n\n<li>PROTECTED&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;<\/li>\n\n\n\n<li>PROVIDES&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;<\/li>\n\n\n\n<li>PUBLIC REQUIRES&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;<\/li>\n\n\n\n<li>RETURN&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;<\/li>\n\n\n\n<li>SHORT<\/li>\n\n\n\n<li>STATIC&nbsp;<\/li>\n\n\n\n<li>STRICTFP&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;<\/li>\n\n\n\n<li>SUPER&nbsp;&nbsp;<\/li>\n\n\n\n<li>SWITCH&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;<\/li>\n\n\n\n<li>SYNCHRONIZED&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; THIS<\/li>\n\n\n\n<li>THROW&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; THROWS&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;<\/li>\n\n\n\n<li>TO&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;<\/li>\n\n\n\n<li>TRANSIENT&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;<\/li>\n\n\n\n<li>TRANSITIVE&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;<\/li>\n\n\n\n<li>TRY<\/li>\n\n\n\n<li>USES&nbsp;&nbsp;&nbsp;&nbsp;<\/li>\n\n\n\n<li>VOID&nbsp;&nbsp;&nbsp;&nbsp;<\/li>\n\n\n\n<li>VOLATILE&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;<\/li>\n\n\n\n<li>WHILE&nbsp;<\/li>\n\n\n\n<li>WITH&nbsp;&nbsp;&nbsp; _<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/bitcamp.it\/blog\/wp-content\/uploads\/2023\/03\/keyword-java-struttura.jpg\" alt=\"Keyword Java\" class=\"wp-image-881\" srcset=\"https:\/\/bitcamp.it\/blog\/wp-content\/uploads\/2023\/03\/keyword-java-struttura.jpg 1200w, https:\/\/bitcamp.it\/blog\/wp-content\/uploads\/2023\/03\/keyword-java-struttura-300x200.jpg 300w, https:\/\/bitcamp.it\/blog\/wp-content\/uploads\/2023\/03\/keyword-java-struttura-1024x683.jpg 1024w, https:\/\/bitcamp.it\/blog\/wp-content\/uploads\/2023\/03\/keyword-java-struttura-768x512.jpg 768w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Quali sono i segni di punteggiatura del linguaggio Java<\/h2>\n\n\n\n<p>Segni di punteggiatura del linguaggio Java sono i seguenti e servono ad <strong>eseguire raggruppamenti e separazioni di istruzioni<\/strong>.<\/p>\n\n\n\n<p>{&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; }&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; [&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; ]&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; (&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; )&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; .&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; ,&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; ;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; \u2026&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; @&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; ::<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Cosa sono i letterali Java<\/h2>\n\n\n\n<p>I letterali si distinguono in<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>numeri interi;<\/li>\n\n\n\n<li>numeri decimali;<\/li>\n\n\n\n<li>i valori booleani true e false;<\/li>\n\n\n\n<li>singoli caratteri Unicode;<\/li>\n\n\n\n<li>stringhe, cio\u00e8 sequenze di caratteri racchiuse tra virgolette doppie;<\/li>\n\n\n\n<li>il riferimento nullo null.<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">Cosa sono gli operatori del linguaggio Java<\/h2>\n\n\n\n<p>Gli operatori indicano un tipo di calcolo da eseguire su uno o pi\u00f9 dati, detti <strong>operandi<\/strong>. Ecco l\u2019elenco degli operatori in Java:<\/p>\n\n\n\n<p>=&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; &gt;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; &lt;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; !&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; ~&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; ?&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; :&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; -&gt;<\/p>\n\n\n\n<p>==&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; &gt;=&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; &lt;=&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; !=&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; &amp;&amp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; ||&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; ++&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; \u2014<\/p>\n\n\n\n<p>+&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; \u2013&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; *&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; \/&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; &amp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; |&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; ^&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; %<\/p>\n\n\n\n<p>&lt;&lt;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; &gt;&gt;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; &gt;&gt;&gt;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; &lt;&lt;=&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; &gt;&gt;=&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; &gt;&gt;&gt;=&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; +=&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; -=<\/p>\n\n\n\n<p>*=&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; \/=&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; &amp;=&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; |=&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; ^=&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; %=<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/bitcamp.it\/blog\/wp-content\/uploads\/2023\/03\/programma-java.jpg\" alt=\"Programma Java\" class=\"wp-image-882\" srcset=\"https:\/\/bitcamp.it\/blog\/wp-content\/uploads\/2023\/03\/programma-java.jpg 1200w, https:\/\/bitcamp.it\/blog\/wp-content\/uploads\/2023\/03\/programma-java-300x200.jpg 300w, https:\/\/bitcamp.it\/blog\/wp-content\/uploads\/2023\/03\/programma-java-1024x683.jpg 1024w, https:\/\/bitcamp.it\/blog\/wp-content\/uploads\/2023\/03\/programma-java-768x512.jpg 768w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Metodi Java: cosa sono e come si usano<\/h2>\n\n\n\n<p>\u00c8 possibile richiamare interi blocchi di istruzioni di codice Java in diverse parti del programma, senza doverle riscrivere ogni volta. Per poterlo fare \u00e8 necessario dare un nome ai <strong>blocchi di codice, chiamati anche metodi<\/strong>.<\/p>\n\n\n\n<p>Essi hanno<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>un\u2019intestazione o specificatore di accesso (public, private);<\/li>\n\n\n\n<li>un tipo di dati restituito che indica il tipo di dato del valore che calcola il metodo (senza espressione \u00e8 void);<\/li>\n\n\n\n<li>un nome (ad esempio max, stampa, dividi)<\/li>\n\n\n\n<li>dei parametri di input dove sono contenuti i dati di ingresso che si indicano con tipo e nome separati da virgole;<\/li>\n\n\n\n<li>dei parametri di output dove sono contenuti i risultati.<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">Esempio di programma Java<\/h2>\n\n\n\n<p>Facciamo un esempio che racchiude tutti i concetti espressi finora e li mette in pratica. Ipotizziamo di voler scrivere un semplice programma Java che restituisce in video la sequenza di caratteri \u201cCiao!\u201d. Ci sar\u00e0 bisogno di una Virtual Machine che funger\u00e0 da interprete del linguaggio Java. Attraverso un editor di testo apriamo un file Ciao.java in cui scrivere il seguente programma:<\/p>\n\n\n\n<p>class Ciao {<\/p>\n\n\n\n<p>public static void main (String[] args) {<\/p>\n\n\n\n<p>System.out.println(&#8220;Ciao!&#8221;);<\/p>\n\n\n\n<p>}<\/p>\n\n\n\n<p>}<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Sei pronto a metterti alla prova con il linguaggio Java creando e sperimentando programmi e applicazioni di qualsiasi tipo? <br><br>Scopri il <a href=\"https:\/\/bitcamp.it\/corso-java-developer.html\" target=\"_blank\" rel=\"noreferrer noopener\">corso bitCamp per sviluppatore Java<\/a> e investi ora nella tua carriera futura con uno dei lavori pi\u00f9 richiesti e pagati del momento!<\/p><\/blockquote><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Vuoi sapere come funziona un programma Java? Leggi la nostra guida completa sulla struttura di un programma Java.<\/p>\n","protected":false},"author":2,"featured_media":879,"comment_status":"closed","ping_status":"closed","sticky":true,"template":"","format":"standard","meta":{"footnotes":""},"categories":[48],"tags":[],"class_list":["post-878","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog-corso-java-fondamenti-e-approfondimenti"],"_links":{"self":[{"href":"https:\/\/bitcamp.it\/blog\/wp-json\/wp\/v2\/posts\/878","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bitcamp.it\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bitcamp.it\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bitcamp.it\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/bitcamp.it\/blog\/wp-json\/wp\/v2\/comments?post=878"}],"version-history":[{"count":4,"href":"https:\/\/bitcamp.it\/blog\/wp-json\/wp\/v2\/posts\/878\/revisions"}],"predecessor-version":[{"id":897,"href":"https:\/\/bitcamp.it\/blog\/wp-json\/wp\/v2\/posts\/878\/revisions\/897"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bitcamp.it\/blog\/wp-json\/wp\/v2\/media\/879"}],"wp:attachment":[{"href":"https:\/\/bitcamp.it\/blog\/wp-json\/wp\/v2\/media?parent=878"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bitcamp.it\/blog\/wp-json\/wp\/v2\/categories?post=878"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bitcamp.it\/blog\/wp-json\/wp\/v2\/tags?post=878"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}